{"id":21829,"date":"2023-04-19T08:00:00","date_gmt":"2023-04-19T11:00:00","guid":{"rendered":"https:\/\/www.produttivo.com.br\/blog\/?p=21829"},"modified":"2025-09-19T18:04:09","modified_gmt":"2025-09-19T21:04:09","slug":"wcm","status":"publish","type":"post","link":"https:\/\/www.produttivo.com.br\/blog\/wcm\/","title":{"rendered":"WCM: o que \u00e9, principais pilares e como aplicar na empresa"},"content":{"rendered":"\n<p>Reduzir custos, cortar desperd\u00edcios e aumentar a efici\u00eancia da produ\u00e7\u00e3o n\u00e3o precisa ser uma meta distante \u2014 existe uma metodologia que transforma essa vis\u00e3o em pr\u00e1tica. <\/p>\n\n\n\n<p>Estamos falando do <strong>WCM (World Class Manufacturing)<\/strong>, um sistema que promove mudan\u00e7a cultural completa na empresa com base em pilares estrat\u00e9gicos.<\/p>\n\n\n\n<p>Mais do que uma ferramenta de produtividade, o WCM fortalece a <a href=\"https:\/\/www.produttivo.com.br\/blog\/gestao-da-qualidade\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>gest\u00e3o da qualidade<\/strong><\/a> e pode ser aplicado em toda a opera\u00e7\u00e3o, do setor de produ\u00e7\u00e3o ao de manuten\u00e7\u00e3o.<\/p>\n\n\n\n<p><strong>Neste artigo, voc\u00ea vai entender o que \u00e9 o WCM, conhecer seus principais conceitos e aprender como aplic\u00e1-lo para elevar a competitividade da sua empresa.<\/strong><\/p>\n\n\n\n<p>Quando a excel\u00eancia operacional vira parte da cultura, a empresa n\u00e3o apenas reduz custos, mas conquista vantagem competitiva sustent\u00e1vel.<\/p>\n\n\n\n<p class=\"has-text-align-center\">Veja tamb\u00e9m: <strong><a href=\"https:\/\/www.produttivo.com.br\/software-de-manutencao\/?utm_source=blog&amp;utm_medium=organic&amp;utm_term=postWCM&amp;utm_campaign=PostWCM\" target=\"_blank\" rel=\"noreferrer noopener\">Software de manuten\u00e7\u00e3o para controle autom\u00e1tico de servi\u00e7os<\/a><\/strong><\/p>\n\n\n\t\t\t\t<div class=\"wp-block-uagb-table-of-contents uagb-toc__align-left uagb-toc__columns-1  uagb-block-59abd085      \"\n\t\t\t\t\tdata-scroll= \"1\"\n\t\t\t\t\tdata-offset= \"30\"\n\t\t\t\t\tstyle=\"\"\n\t\t\t\t>\n\t\t\t\t<div class=\"uagb-toc__wrap\">\n\t\t\t\t\t\t<div class=\"uagb-toc__title\">\n\t\t\t\t\t\t\tO que voc\u00ea vai ver neste conte\u00fado: \t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"uagb-toc__list-wrap \">\n\t\t\t\t\t\t<ol class=\"uagb-toc__list\"><li class=\"uagb-toc__list\"><a href=\"#wcm-o-que-\u00e9\" class=\"uagb-toc-link__trigger\">WCM o que \u00e9?<\/a><li class=\"uagb-toc__list\"><a href=\"#benef\u00edcios-da-gest\u00e3o-wcm-nas-empresas\" class=\"uagb-toc-link__trigger\">Benef\u00edcios da gest\u00e3o WCM nas empresas\u00a0<\/a><li class=\"uagb-toc__list\"><a href=\"#como-implementar-a-metodologia-wcm-na-sua-empresa\" class=\"uagb-toc-link__trigger\">Como implementar a metodologia WCM na sua empresa?<\/a><li class=\"uagb-toc__list\"><a href=\"#como-\u00e9-o-sistema-de-avalia\u00e7\u00e3o-wcm\" class=\"uagb-toc-link__trigger\">Como \u00e9 o sistema de avalia\u00e7\u00e3o WCM?<\/a><li class=\"uagb-toc__list\"><a href=\"#quais-s\u00e3o-os-pilares-do-wcm\" class=\"uagb-toc-link__trigger\">Quais s\u00e3o os pilares do WCM?<\/a><li class=\"uagb-toc__list\"><a href=\"#quais-s\u00e3o-as-7-ferramentas-wcm\" class=\"uagb-toc-link__trigger\">Quais s\u00e3o as 7 ferramentas WCM?\u00a0<\/a><li class=\"uagb-toc__list\"><a href=\"#curso-wcm-quais-s\u00e3o-as-certifica\u00e7\u00f5es\" class=\"uagb-toc-link__trigger\">Curso WCM: Quais s\u00e3o as certifica\u00e7\u00f5es?\u00a0<\/a><\/ol>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>WCM o que \u00e9?<\/strong><\/h2>\n\n\n\n<p>O <strong>WCM<\/strong> (World Class Manufacturing) \u00e9 uma metodologia que re\u00fane princ\u00edpios e t\u00e9cnicas de <a href=\"https:\/\/www.produttivo.com.br\/blog\/gestao-de-servicos\/\" target=\"_blank\" rel=\"noreferrer noopener\">gest\u00e3o<\/a> a serem aplicadas em empresas com o objetivo de<strong> eliminar desperd\u00edcios, reduzir custos e melhorar processos.&nbsp;<\/strong><\/p>\n\n\n\n<p>Baseado no sistema Lean, o WCM sofreu adapta\u00e7\u00f5es para se encaixar nas caracter\u00edsticas e necessidades do mercado ocidental, buscando estimular a <strong>melhoria cont\u00ednua<\/strong> nas empresas, de tal forma que elas sejam consideradas empresas de \u201cclasse mundial\u201d, ou seja, que n\u00e3o s\u00f3 consigam se destacar no mercado, como liderar o segmento em que s\u00e3o especialistas, entregando produtos de qualidade, com zero desperd\u00edcio.&nbsp;<\/p>\n\n\n\n<p>Al\u00e9m dos resultados obtidos com a ado\u00e7\u00e3o do WCM, as empresas tamb\u00e9m podem ser premiadas com certifica\u00e7\u00f5es, sendo elas: bronze, prata, ouro e World Class. Conforme os resultados obtidos \u00e9 poss\u00edvel chegar mais longe na certifica\u00e7\u00e3o.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-style-default\"><a href=\"https:\/\/materiais.produttivo.com.br\/plano-de-manutencao-preventiva-excel\/?utm_source=blog&amp;utm_medium=organic&amp;utm_term=postWCM&amp;utm_campaign=PostWCM\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" width=\"1024\" height=\"536\" data-src=\"https:\/\/www.produttivo.com.br\/blog\/wp-content\/uploads\/2023\/04\/kit-plano-de-manutencao-para-baixar-gratuitamente-1024x536.webp\" alt=\"kit plano de manuten\u00e7\u00e3o para baixar gratuitamente\" class=\"wp-image-21830 lazyload\" data-srcset=\"https:\/\/www.produttivo.com.br\/blog\/wp-content\/uploads\/2023\/04\/kit-plano-de-manutencao-para-baixar-gratuitamente-1024x536.webp 1024w, https:\/\/www.produttivo.com.br\/blog\/wp-content\/uploads\/2023\/04\/kit-plano-de-manutencao-para-baixar-gratuitamente-300x157.webp 300w, https:\/\/www.produttivo.com.br\/blog\/wp-content\/uploads\/2023\/04\/kit-plano-de-manutencao-para-baixar-gratuitamente.webp 1200w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/536;\" \/><\/a><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Qual a diferen\u00e7a entre TPM e WCM?&nbsp;<\/strong><\/h3>\n\n\n\n<p>A <a href=\"https:\/\/www.produttivo.com.br\/blog\/tpm-manutencao\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>manuten\u00e7\u00e3o produtiva total (TPM)<\/strong><\/a> \u00e9 um conjunto de a\u00e7\u00f5es que t\u00eam como objetivo minimizar erros e aumentar a produtividade de equipamentos atrav\u00e9s do estabelecimento de <strong>rotinas de manuten\u00e7\u00e3o<\/strong> e do <strong>acompanhamento de performance dos ativos.&nbsp;<\/strong><\/p>\n\n\n\n<p>J\u00e1 o WCM, como vimos, \u00e9 uma metodologia que pode ser aplicada em todo o processo produtivo, independente do setor. Seu prop\u00f3sito \u00e9 alcan\u00e7ar excel\u00eancia operacional na produ\u00e7\u00e3o, no controle de qualidade, na log\u00edstica e nas rotinas de <a href=\"https:\/\/www.produttivo.com.br\/blog\/tipos-de-manutencao-quais-suas-diferencas\/\" target=\"_blank\" rel=\"noreferrer noopener\">manuten\u00e7\u00e3o.<\/a>&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Qual a diferen\u00e7a entre Lean e WCM?&nbsp;<\/strong><\/h3>\n\n\n\n<p>O WCM surgiu a partir do sistema Lean, replicando para a sua metodologia o conceito j\u00e1 consolidado de melhoria cont\u00ednua. A diferen\u00e7a \u00e9 que a metodologia <strong>WCM<\/strong> foi criada especialmente para <strong>atender as necessidades e caracter\u00edsticas do mercado ocidental,<\/strong> que demandava resultados r\u00e1pidos, utilizando a menor quantidade de recursos poss\u00edveis.&nbsp;<\/p>\n\n\n\n<p>Outra diferen\u00e7a \u00e9 que o sistema Lean se baseia apenas em princ\u00edpios, e os resultados que s\u00e3o alcan\u00e7ados a partir dessa metodologia n\u00e3o est\u00e3o atrelados a ferramentas definidas. J\u00e1 o WCM possui <strong>ferramentas bem definidas<\/strong> para ado\u00e7\u00e3o da metodologia, al\u00e9m de <strong>mecanismos de classifica\u00e7\u00e3o e avalia\u00e7\u00e3o<\/strong> por meio de <a href=\"https:\/\/www.produttivo.com.br\/blog\/o-que-e-auditoria\/\" target=\"_blank\" rel=\"noreferrer noopener\">auditorias<\/a>.&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-center\">Veja tamb\u00e9m: <a href=\"https:\/\/www.produttivo.com.br\/blog\/depreciacao-de-maquinas-e-equipamentos\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Deprecia\u00e7\u00e3o de m\u00e1quinas e equipamentos: como calcular e evitar<\/strong><\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Benef\u00edcios da gest\u00e3o WCM nas empresas&nbsp;<\/strong><\/h2>\n\n\n\n<p>Ao implementar o WCM as empresas podem ver<strong> resultados consistentes<\/strong> em todos os setores, como:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Redu\u00e7\u00e3o nos <a href=\"https:\/\/www.produttivo.com.br\/blog\/custo-de-manutencao\/\" target=\"_blank\" rel=\"noreferrer noopener\">custos de manuten\u00e7\u00e3o<\/a>;<\/li><li>Melhora de <a href=\"https:\/\/www.produttivo.com.br\/blog\/inspecao-de-seguranca\/\" target=\"_blank\" rel=\"noreferrer noopener\">seguran\u00e7a<\/a> para os operadores;&nbsp;<\/li><li>Diminui\u00e7\u00e3o de desperd\u00edcios;<\/li><li>Melhora na qualidade dos produtos;&nbsp;<\/li><li>Redu\u00e7\u00e3o na necessidade de <a href=\"https:\/\/www.produttivo.com.br\/blog\/manutencao-corretiva-boas-praticas\/\" target=\"_blank\" rel=\"noreferrer noopener\">manuten\u00e7\u00f5es corretivas<\/a>;&nbsp;<\/li><li>Resolu\u00e7\u00e3o de problemas feitos de maneira mais r\u00e1pida;&nbsp;&nbsp;<\/li><li>Otimiza\u00e7\u00e3o de processos;<\/li><li>Aumento de produtividade;&nbsp;<\/li><li>Melhora no desempenho dos <a href=\"https:\/\/www.produttivo.com.br\/blog\/gestao-de-ativos-o-passo-a-passo-para-gerar-resultados\/\" target=\"_blank\" rel=\"noreferrer noopener\">ativos<\/a>;&nbsp;<\/li><li>Redu\u00e7\u00e3o de paradas n\u00e3o programadas;<\/li><li>Aumento de satisfa\u00e7\u00e3o dos clientes;&nbsp;<\/li><li>Redu\u00e7\u00e3o de lead time;<\/li><li>Redu\u00e7\u00e3o de produtos em estoque;&nbsp;<\/li><li>Entre outros.&nbsp;<\/li><\/ul>\n\n\n\n<p class=\"has-text-align-center\"><a href=\"https:\/\/materiais.produttivo.com.br\/plano-de-manutencao-preventiva-excel\/?utm_source=blog&amp;utm_medium=organic&amp;utm_term=postWCM&amp;utm_campaign=PostWCM\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Otimize os resultados de manuten\u00e7\u00e3o atrav\u00e9s do nosso plano de manuten\u00e7\u00e3o para baixar gratuitamente<\/strong><\/a><strong>&nbsp;<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-style-default\"><a href=\"https:\/\/materiais.produttivo.com.br\/plano-de-manutencao-preventiva-excel\/?utm_source=blog&amp;utm_medium=organic&amp;utm_term=postWCM&amp;utm_campaign=PostWCM\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" width=\"1024\" height=\"536\" data-src=\"https:\/\/www.produttivo.com.br\/blog\/wp-content\/uploads\/2023\/04\/kit-plano-de-manutencao-para-baixar-gratuitamente-1024x536.webp\" alt=\"kit plano de manuten\u00e7\u00e3o para baixar gratuitamente\" class=\"wp-image-21830 lazyload\" data-srcset=\"https:\/\/www.produttivo.com.br\/blog\/wp-content\/uploads\/2023\/04\/kit-plano-de-manutencao-para-baixar-gratuitamente-1024x536.webp 1024w, https:\/\/www.produttivo.com.br\/blog\/wp-content\/uploads\/2023\/04\/kit-plano-de-manutencao-para-baixar-gratuitamente-300x157.webp 300w, https:\/\/www.produttivo.com.br\/blog\/wp-content\/uploads\/2023\/04\/kit-plano-de-manutencao-para-baixar-gratuitamente.webp 1200w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/536;\" \/><\/a><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Como implementar a metodologia WCM na sua empresa?<\/strong><\/h2>\n\n\n\n<p>A implementa\u00e7\u00e3o do WCM nas organiza\u00e7\u00f5es deve <strong>come\u00e7ar com uma \u00e1rea modelo,<\/strong> para s\u00f3 ent\u00e3o se expandir para outros setores da empresa.&nbsp;<\/p>\n\n\n\n<p>Isso acontece porque a metodologia \u00e9 complexa e repleta de detalhes, al\u00e9m disso os gestores conseguem ter mais controle sobre sua aplica\u00e7\u00e3o e sobre os resultados alcan\u00e7ados, conseguindo empregar os aprendizados nas pr\u00f3ximas etapas.&nbsp;<\/p>\n\n\n\n<p>Separamos um <strong>passo a passo<\/strong> que vai te ajudar a come\u00e7ar a implementar as t\u00e9cnicas do WCM na sua empresa, confira:&nbsp;<\/p>\n\n\n\n<ol class=\"wp-block-list\"><li><strong>Escolha a \u00e1rea que servir\u00e1 de modelo <\/strong>para a implementa\u00e7\u00e3o do WCM. Opte pelo setor que apresenta mais problemas, resultados insatisfat\u00f3rios ou os gargalos mais recorrentes, porque ser\u00e3o \u00e1reas que apresentar\u00e3o maiores oportunidades de melhorias;<\/li><li>Comece a estrutura a aplica\u00e7\u00e3o da metodologia atrav\u00e9s de um <strong>planejamento<\/strong> que leve em conta todos os <strong>princ\u00edpios do WCM <\/strong>(mais para frente elencamos todos os princ\u00edpios para voc\u00ea n\u00e3o esquecer de nenhum);<\/li><li>Entenda e <strong>defina quais a\u00e7\u00f5es<\/strong> podem ser implementadas levando em conta os princ\u00edpios do WCM e os objetivos da empresa (redu\u00e7\u00e3o de falhas, perdas, desperd\u00edcios, defeitos, <a href=\"https:\/\/www.produttivo.com.br\/blog\/gestao-de-residuos\/\" target=\"_blank\" rel=\"noreferrer noopener\">gera\u00e7\u00e3o de res\u00edduos<\/a>, etc);<\/li><li><strong>Capacite os profissionais<\/strong> da \u00e1rea oferecendo treinamentos sobre WCM para que conhe\u00e7am e apliquem as ferramentas necess\u00e1rias;&nbsp;<\/li><li>Garanta que <strong>profissionais altamente qualificados<\/strong> sejam alocados para esse setor e que eles auxiliem na implementa\u00e7\u00e3o das t\u00e9cnicas de WCM;&nbsp;<\/li><li><strong>Use ferramentas <\/strong>que possam auxiliar na implementa\u00e7\u00e3o dos princ\u00edpios do WCM (mais adiante falaremos de algumas delas detalhadamente). S\u00e3o exemplos o <a href=\"https:\/\/www.produttivo.com.br\/blog\/fmea\/\" target=\"_blank\" rel=\"noreferrer noopener\">FMEA<\/a>, <a href=\"https:\/\/www.produttivo.com.br\/blog\/matriz-gut\/\" target=\"_blank\" rel=\"noreferrer noopener\">Matriz GUT<\/a>, 5s 5t, Poka Yoke, Kanban e <a href=\"https:\/\/www.produttivo.com.br\/blog\/analise-de-causa-raiz\/\" target=\"_blank\" rel=\"noreferrer noopener\">an\u00e1lise de causa raiz<\/a>.&nbsp;&nbsp;<\/li><\/ol>\n\n\n\n<p>Usando um <strong>exemplo pr\u00e1tico para aplica\u00e7\u00e3o dos passos do WCM<\/strong>, temos um setor de <a href=\"https:\/\/www.produttivo.com.br\/blog\/guia-manutencao-industrial-o-que-faz\/\" target=\"_blank\" rel=\"noreferrer noopener\">manuten\u00e7\u00e3o industrial<\/a> cujo principal problema \u00e9 resolver as constantes quebras, falhas e defeitos de um maquin\u00e1rio. Nesse caso o passo a passo ficaria da seguinte forma:&nbsp;<\/p>\n\n\n\n<ol class=\"wp-block-list\"><li>O setor escolhido para come\u00e7ar com o WCM foi o setor de manuten\u00e7\u00e3o, devido \u00e0s constantes quebras e falhas de maquin\u00e1rio, que impactam a produ\u00e7\u00e3o e a qualidade dos produtos.<\/li><li>Para resolu\u00e7\u00e3o do problema do maquin\u00e1rio, as a\u00e7\u00f5es ser\u00e3o desenvolvidas com base nos pilares de manuten\u00e7\u00e3o aut\u00f4noma, manuten\u00e7\u00e3o planejada e gest\u00e3o preventiva dos equipamentos;&nbsp;<\/li><li>Dentro dos princ\u00edpios as a\u00e7\u00f5es escolhidas para serem implementadas foram:&nbsp;<ol><li><a href=\"https:\/\/www.produttivo.com.br\/blog\/manutencao-autonoma\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Manuten\u00e7\u00e3o aut\u00f4noma:<\/strong><\/a> Capacita\u00e7\u00e3o dos profissionais e ado\u00e7\u00e3o de rotinas de inspe\u00e7\u00e3o, limpeza e lubrifica\u00e7\u00e3o para o equipamento;&nbsp;<\/li><li><a href=\"https:\/\/www.produttivo.com.br\/blog\/manutencao-planejada\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Manuten\u00e7\u00e3o planejada:<\/strong><\/a> An\u00e1lise da causa raiz das quebras do equipamento e cria\u00e7\u00e3o de um plano de manuten\u00e7\u00e3o para o ativo, estabelecendo a periodicidade de realiza\u00e7\u00e3o das manuten\u00e7\u00f5es;&nbsp;<\/li><li><strong>Gest\u00e3o preventiva dos equipamentos:<\/strong> Envolvimento da \u00e1rea de engenharia nos projetos dos equipamentos, integra\u00e7\u00e3o de fornecedores no projeto, desenvolvimento e monitoramento de todas as etapas do projeto;<\/li><\/ol><\/li><li>Foram estabelecidos treinamentos para os operadores, manutentores e demais envolvidos no setor de manuten\u00e7\u00e3o que cuida do ativo;&nbsp;<\/li><li>Profissionais altamente qualificados foram direcionados ao setor;&nbsp;<\/li><li>As ferramentas utilizadas foram: an\u00e1lise de causa raiz, FMEA, ciclo PDCA e matriz GUT.&nbsp;<\/li><\/ol>\n\n\n\n<p>Assim que o WCM for aplicado, surgir\u00e3o<strong> aprendizados que podem ser aplicados para outras \u00e1reas<\/strong> e as melhores pr\u00e1ticas adotadas podem ser disseminadas por toda a empresa.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large is-style-default\"><a href=\"https:\/\/www.produttivo.com.br\/modelo\/checklist-manutencao-preventiva\/?utm_source=blog&amp;utm_medium=organic&amp;utm_term=postWCM&amp;utm_campaign=PostWCM\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" width=\"1024\" height=\"535\" data-id=\"21831\" data-src=\"https:\/\/www.produttivo.com.br\/blog\/wp-content\/uploads\/2023\/04\/Checklist-Digital-de-Manutencao-Preventiva-para-usar-em-aplicativo-1024x535.webp\" alt=\"Checklist Digital de Manuten\u00e7\u00e3o Preventiva para usar em aplicativo\" class=\"wp-image-21831 lazyload\" data-srcset=\"https:\/\/www.produttivo.com.br\/blog\/wp-content\/uploads\/2023\/04\/Checklist-Digital-de-Manutencao-Preventiva-para-usar-em-aplicativo-1024x535.webp 1024w, https:\/\/www.produttivo.com.br\/blog\/wp-content\/uploads\/2023\/04\/Checklist-Digital-de-Manutencao-Preventiva-para-usar-em-aplicativo-300x157.webp 300w, https:\/\/www.produttivo.com.br\/blog\/wp-content\/uploads\/2023\/04\/Checklist-Digital-de-Manutencao-Preventiva-para-usar-em-aplicativo.webp 1200w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/535;\" \/><\/a><\/figure>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Como \u00e9 o sistema de avalia\u00e7\u00e3o WCM?<\/strong><\/h2>\n\n\n\n<p>A avalia\u00e7\u00e3o do WCM \u00e9 realizada por uma auditoria externa que faz uma an\u00e1lise, duas vezes por ano, sobre os resultados obtidos em cada um dos pilares do WCM.&nbsp;<\/p>\n\n\n\n<p>A <strong>nota vai de 0 a 5 <\/strong>e todos os pilares s\u00e3o avaliados individualmente considerando o n\u00edvel de expans\u00e3o, profundidade e maturidade dos princ\u00edpios adotados.&nbsp;&nbsp;<\/p>\n\n\n\n<p>Atrav\u00e9s das notas a empresa consegue <strong>identificar quais pilares precisam ser aprimorados<\/strong>, quais est\u00e3o em perfeita conformidade e tamb\u00e9m consegue descobrir como est\u00e1 o seu n\u00edvel de implementa\u00e7\u00e3o do WCM, de acordo com a certifica\u00e7\u00e3o que recebe, que pode ser:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Bronze: \u2265 50 pontos;<\/li><li>Prata: \u2265 60 pontos;<\/li><li>Prata: \u2265 60 pontos;<\/li><li>Ouro: \u2265 70 pontos;<\/li><li>World Class: \u2265 85 pontos.<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Quais s\u00e3o os pilares do WCM?<\/strong><\/h2>\n\n\n\n<p>Conhecer os pilares do WCM \u00e9 fundamental para a implementa\u00e7\u00e3o da metodologia nas empresas. Eles s\u00e3o divididos em duas partes, com 10 pontos centrais. Entenda mais sobre cada um:&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Pilares t\u00e9cnicos do WCM&nbsp;<\/strong><\/h3>\n\n\n\n<p>Os pilares t\u00e9cnicos devem ser adotados por todas as etapas de produ\u00e7\u00e3o e tratam sobre tem\u00e1ticas como manuten\u00e7\u00e3o, custos e qualidade. Veja detalhadamente o que cada princ\u00edpio instrui:&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>1. Seguran\u00e7a<\/strong><\/h4>\n\n\n\n<p>Tem como objetivo melhorar a <strong>seguran\u00e7a no local de trabalho,<\/strong> diminuindo os riscos de acidentes, reduzindo a incid\u00eancia de atos inseguros. Tamb\u00e9m busca desenvolver uma cultura preventiva, assegurando a integridade e o bem-estar dos operadores.&nbsp;<\/p>\n\n\n\n<p>Para a sua aplica\u00e7\u00e3o podem ser desenvolvidas <a href=\"https:\/\/www.produttivo.com.br\/blog\/analise-de-riscos\/\" target=\"_blank\" rel=\"noreferrer noopener\">an\u00e1lises de riscos<\/a>, cria\u00e7\u00e3o de <a href=\"https:\/\/www.produttivo.com.br\/blog\/mapa-de-riscos\/\" target=\"_blank\" rel=\"noreferrer noopener\">mapas de riscos<\/a> e realiza\u00e7\u00e3o de <a href=\"https:\/\/www.produttivo.com.br\/blog\/manutencao-preditiva-o-que-e-exemplos-e-tendencias-do-setor\/\" target=\"_blank\" rel=\"noreferrer noopener\">manuten\u00e7\u00f5es preditivas<\/a> em equipamentos.&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>2. Desdobramento de custos<\/strong><\/h4>\n\n\n\n<p>No desdobramento de custos do WCM a empresa deve mapear todos os <strong>custos<\/strong> desnecess\u00e1rios para que <strong>sejam reduzidos <\/strong>ao m\u00e1ximo, come\u00e7ando por aqueles que geram mais perdas e oferecem maior potencial de redu\u00e7\u00e3o.&nbsp;<\/p>\n\n\n\n<p>Como a\u00e7\u00f5es pr\u00e1ticas \u00e9 poss\u00edvel realizar a matriz de perdas, definir o or\u00e7amento dos pr\u00f3ximos meses ou do pr\u00f3ximo ano e estruturar um plano de redu\u00e7\u00e3o de custos.&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>3. Melhoria cont\u00ednua<\/strong><\/h4>\n\n\n\n<p>A melhoria cont\u00ednua defende a constante ado\u00e7\u00e3o de t\u00e9cnicas, estrat\u00e9gias e ferramentas para que a <strong>evolu\u00e7\u00e3o da organiza\u00e7\u00e3o<\/strong> n\u00e3o tenha fim e sempre esteja sendo aprimorada. \u00c9 atrav\u00e9s dela que h\u00e1 a <strong>melhora de performance<\/strong> e a identifica\u00e7\u00e3o dos m\u00e9todos certos para cada problema encontrado.&nbsp;<\/p>\n\n\n\n<p>Para implement\u00e1-la realize treinamentos, monitore o andamento de projetos e valide resultados de outras a\u00e7\u00f5es e experimentos que foram feitos, pensando nas pr\u00f3ximas aplica\u00e7\u00f5es.&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>4. Manuten\u00e7\u00e3o Aut\u00f4noma<\/strong><\/h4>\n\n\n\n<p>A manuten\u00e7\u00e3o aut\u00f4noma se traduz na capacita\u00e7\u00e3o dos operadores para a realiza\u00e7\u00e3o de uma manuten\u00e7\u00e3o eficiente, na <strong>melhora da disponibilidade e desempenho dos equipamentos <\/strong>e na realiza\u00e7\u00e3o de rotinas recorrentes de <a href=\"https:\/\/www.produttivo.com.br\/blog\/check-list-de-limpeza\/\" target=\"_blank\" rel=\"noreferrer noopener\">limpeza<\/a>, lubrifica\u00e7\u00e3o, <a href=\"https:\/\/www.produttivo.com.br\/blog\/guia-da-inspecao\/\" target=\"_blank\" rel=\"noreferrer noopener\">inspe\u00e7\u00f5es<\/a> e demais ajustes pontuais.&nbsp;<\/p>\n\n\n\n<p>Com isso, se pretende reduzir a incid\u00eancia de quebras e falhas, melhorar a <a href=\"https:\/\/www.produttivo.com.br\/blog\/oee\/\" target=\"_blank\" rel=\"noreferrer noopener\">efici\u00eancia global (OEE) das m\u00e1quinas<\/a>, garantir maior qualidade nos produtos e aumentar a vida \u00fatil dos ativos.&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>5. Manuten\u00e7\u00e3o Planejada<\/strong><\/h4>\n\n\n\n<p>Ao restaurar as condi\u00e7\u00f5es de funcionamento dos equipamentos, a manuten\u00e7\u00e3o planejada busca <strong>aumentar a efici\u00eancia e reduzir custos de manuten\u00e7\u00e3o,<\/strong> fazendo com que o<a href=\"https:\/\/www.produttivo.com.br\/blog\/mtbf-e-mttr\/\" target=\"_blank\" rel=\"noreferrer noopener\"> MTB aumente e o MTTR diminua.<\/a><\/p>\n\n\n\n<p>As a\u00e7\u00f5es adotadas consistem na elabora\u00e7\u00e3o de um <a href=\"https:\/\/www.produttivo.com.br\/blog\/como-fazer-um-plano-de-manutencao-eficiente\/\" target=\"_blank\" rel=\"noreferrer noopener\">plano de manuten\u00e7\u00e3o<\/a> preventiva, an\u00e1lise de causa raiz e realiza\u00e7\u00e3o de atividades que recuperem as condi\u00e7\u00f5es originais dos maquin\u00e1rios.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-style-default\"><a href=\"https:\/\/materiais.produttivo.com.br\/plano-de-manutencao-preventiva-excel\/?utm_source=blog&amp;utm_medium=organic&amp;utm_term=postWCM&amp;utm_campaign=PostWCM\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" width=\"1024\" height=\"536\" data-src=\"https:\/\/www.produttivo.com.br\/blog\/wp-content\/uploads\/2023\/04\/kit-plano-de-manutencao-para-baixar-gratuitamente-1024x536.webp\" alt=\"kit plano de manuten\u00e7\u00e3o para baixar gratuitamente\" class=\"wp-image-21830 lazyload\" data-srcset=\"https:\/\/www.produttivo.com.br\/blog\/wp-content\/uploads\/2023\/04\/kit-plano-de-manutencao-para-baixar-gratuitamente-1024x536.webp 1024w, https:\/\/www.produttivo.com.br\/blog\/wp-content\/uploads\/2023\/04\/kit-plano-de-manutencao-para-baixar-gratuitamente-300x157.webp 300w, https:\/\/www.produttivo.com.br\/blog\/wp-content\/uploads\/2023\/04\/kit-plano-de-manutencao-para-baixar-gratuitamente.webp 1200w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/536;\" \/><\/a><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>6. Controle de qualidade<\/strong><\/h4>\n\n\n\n<p>O controle de qualidade deve garantir a <strong>m\u00e1xima qualidade dos produtos e satisfa\u00e7\u00e3o dos clientes com o m\u00ednimo de custo de produ\u00e7\u00e3o<\/strong>. Por isso, deve alinhar vari\u00e1veis envolvidas no processo, reduzir estoques e com eles reduzir tamb\u00e9m as possibilidades de danos aos produtos.&nbsp;<\/p>\n\n\n\n<p>Os resultados podem ser observados na redu\u00e7\u00e3o de defeitos, refugos e retrabalhos e no aumento do <a href=\"https:\/\/www.produttivo.com.br\/blog\/nps\/\" target=\"_blank\" rel=\"noreferrer noopener\">NPS<\/a> e outros mecanismos de <a href=\"https:\/\/www.produttivo.com.br\/blog\/pesquisa-de-satisfacao\/\" target=\"_blank\" rel=\"noreferrer noopener\">pesquisa de satisfa\u00e7\u00e3o<\/a> do cliente.&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>7. Log\u00edstica e servi\u00e7o ao cliente<\/strong><\/h4>\n\n\n\n<p>Implementando uma boa gest\u00e3o log\u00edstica o <strong>lead time \u00e9 reduzido<\/strong>, assim como os n\u00edveis de estoque que, por sua vez, t\u00eam um impacto direto na redu\u00e7\u00e3o de custos. Al\u00e9m disso, as movimenta\u00e7\u00f5es internas s\u00e3o minimizadas e os fluxos de atendimento ao cliente ficam mais enxutos.<\/p>\n\n\n\n<p>Para aprimorar a log\u00edstica, a empresa pode apostar em mapeamentos de fluxo de valor, melhorar os sistemas de programa\u00e7\u00e3o interna e externa, os layouts e as embalagens.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>8. Gest\u00e3o preventiva dos equipamentos<\/strong><\/h4>\n\n\n\n<p>A gest\u00e3o preventiva dos equipamentos deve ter como foco o <strong>aumento da <\/strong><a href=\"https:\/\/www.produttivo.com.br\/blog\/o-que-e-confiabilidade\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>confiabilidade<\/strong><\/a><strong>,<\/strong> a diminui\u00e7\u00e3o do <a href=\"https:\/\/www.produttivo.com.br\/blog\/lcc-custo-de-ciclo-de-vida\/\" target=\"_blank\" rel=\"noreferrer noopener\">custo de vida<\/a> e a redu\u00e7\u00e3o da necessidade de manuten\u00e7\u00e3o dos ativos.<\/p>\n\n\n\n<p>As a\u00e7\u00f5es adotadas devem se preocupar em reduzir o lead time entre a concep\u00e7\u00e3o e produ\u00e7\u00e3o, melhorar a curva de aprendizado do equipamento e, consequentemente, seu desempenho. Al\u00e9m de adquirir novos equipamentos que sejam refer\u00eancias em custo, qualidade, produtividade e facilidade de manuten\u00e7\u00e3o.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-style-default\"><a href=\"https:\/\/materiais.produttivo.com.br\/plano-de-manutencao-preventiva-excel\/?utm_source=blog&amp;utm_medium=organic&amp;utm_term=postWCM&amp;utm_campaign=PostWCM\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" width=\"1024\" height=\"536\" data-src=\"https:\/\/www.produttivo.com.br\/blog\/wp-content\/uploads\/2023\/04\/kit-plano-de-manutencao-para-baixar-gratuitamente-1024x536.webp\" alt=\"kit plano de manuten\u00e7\u00e3o para baixar gratuitamente\" class=\"wp-image-21830 lazyload\" data-srcset=\"https:\/\/www.produttivo.com.br\/blog\/wp-content\/uploads\/2023\/04\/kit-plano-de-manutencao-para-baixar-gratuitamente-1024x536.webp 1024w, https:\/\/www.produttivo.com.br\/blog\/wp-content\/uploads\/2023\/04\/kit-plano-de-manutencao-para-baixar-gratuitamente-300x157.webp 300w, https:\/\/www.produttivo.com.br\/blog\/wp-content\/uploads\/2023\/04\/kit-plano-de-manutencao-para-baixar-gratuitamente.webp 1200w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/536;\" \/><\/a><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>9. Desenvolvimento de pessoas<\/strong><\/h4>\n\n\n\n<p>Para que o WCM tenha sucesso e ades\u00e3o nas empresas, \u00e9 preciso que todos os <strong>colaboradores sejam capacitados e treinados<\/strong> para implementar os conceitos difundidos pelo WCM, se preocupando em reduzir todos os problemas relacionados a erros humanos e atos inseguros.&nbsp;<\/p>\n\n\n\n<p>Para que isso ocorra \u00e9 necess\u00e1rio mapear conhecimentos e a\u00e7\u00f5es que tiveram resultados positivos durante a implementa\u00e7\u00e3o do WMC, analisar gaps e ter um plano de treinamento para desenvolver compet\u00eancias essenciais dos colaboradores, bem como apresentar ferramentas que v\u00e3o auxiliar na resolu\u00e7\u00e3o de problemas.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>10. Meio ambiente e energia&nbsp;<\/strong><\/h4>\n\n\n\n<p>O \u00faltimo pilar t\u00e9cnico do WCM trata do uso correto de recursos naturais e materiais da empresa. Como foco principal est\u00e1 a <strong>redu\u00e7\u00e3o do consumo de energia<\/strong>, o uso de energias alternativas, a promo\u00e7\u00e3o de conscientiza\u00e7\u00e3o ambiental e a restaura\u00e7\u00e3o de equipamentos que t\u00eam grande consumo.&nbsp;<\/p>\n\n\n\n<p>Para colocar o pilar em pr\u00e1tica, realize auditorias internas focadas no cumprimento das exig\u00eancias da norma ISO 14001, mapeie e controle o consumo de <a href=\"https:\/\/www.produttivo.com.br\/blog\/eficiencia-energetica\/\" target=\"_blank\" rel=\"noreferrer noopener\">energia<\/a> de cada equipamento e melhore as condi\u00e7\u00f5es dos ativos.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Pilares gerenciais do WCM<\/strong><\/h3>\n\n\n\n<p>O WCM, antes de tudo, precisa ser uma <strong>filosofia praticada pelas lideran\u00e7as.<\/strong> Por isso, o segundo pilar desta metodologia est\u00e1 relacionado ao comprometimento que gestores e ger\u00eancias devem demonstrar. Veja o que cada um dos pilares gerenciais orientam:<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>1. Comprometimento gerencial<\/strong><\/h4>\n\n\n\n<p>O comprometimento geral ressalta a necessidade do <strong>envolvimento das lideran\u00e7as<\/strong> com as ferramentas, princ\u00edpios e metodologias utilizadas no WCM. Afinal, quando os l\u00edderes est\u00e3o engajados \u00e9 muito mais f\u00e1cil engajar os colaboradores tamb\u00e9m.&nbsp;<\/p>\n\n\n\n<p>Ou seja, \u00e9 preciso que o WCM seja uma filosofia na empresa, direcionando todas as atitudes da lideran\u00e7a, mudando e remodelando a cultura da organiza\u00e7\u00e3o, das mais altas hierarquias at\u00e9 o ch\u00e3o de f\u00e1brica.&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>2. Clareza de objetivos<\/strong><\/h4>\n\n\n\n<p>Outro ponto que impacta no engajamento e direcionamento da equipe s\u00e3o os objetivos. Logo, eles devem <strong>estar claros e serem muito bem constru\u00eddos<\/strong> desde o in\u00edcio da aplica\u00e7\u00e3o do WCM, pois eles v\u00e3o nortear todas as a\u00e7\u00f5es subsequentes.&nbsp;<\/p>\n\n\n\n<p>Ao determinar os objetivos \u00e9 preciso que as lideran\u00e7as mostrem os par\u00e2metros e resultados esperados e o caminho para alcan\u00e7\u00e1-los.&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>3. Mapeamento das etapas para o WCM<\/strong><\/h4>\n\n\n\n<p>Logo em seguida dos objetivos, deve vir o mapeamento, que serve como um planejamento que determina<strong> como ser\u00e1 a implementa\u00e7\u00e3o do WCM<\/strong>, quais <a href=\"https:\/\/www.produttivo.com.br\/blog\/dados-e-indicadores-para-gestao-de-servicos-externos\/\" target=\"_blank\" rel=\"noreferrer noopener\">indicadores<\/a> devem ser acompanhados e os resultados esperados.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-style-default\"><a href=\"https:\/\/materiais.produttivo.com.br\/modelo-checklist\/?utm_source=blog&amp;utm_medium=organic&amp;utm_term=postWCM&amp;utm_campaign=PostWCM\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" width=\"1024\" height=\"535\" data-src=\"https:\/\/www.produttivo.com.br\/blog\/wp-content\/uploads\/2023\/04\/Kit-checklist-de-manutencao-para-baixar-1024x535.webp\" alt=\"kit checklist de manuten\u00e7\u00e3o para baixar gratuitamente\" class=\"wp-image-21778 lazyload\" data-srcset=\"https:\/\/www.produttivo.com.br\/blog\/wp-content\/uploads\/2023\/04\/Kit-checklist-de-manutencao-para-baixar-1024x535.webp 1024w, https:\/\/www.produttivo.com.br\/blog\/wp-content\/uploads\/2023\/04\/Kit-checklist-de-manutencao-para-baixar-300x157.webp 300w, https:\/\/www.produttivo.com.br\/blog\/wp-content\/uploads\/2023\/04\/Kit-checklist-de-manutencao-para-baixar.webp 1200w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/535;\" \/><\/a><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>4. Aloca\u00e7\u00e3o de pessoas qualificadas<\/strong><\/h4>\n\n\n\n<p>Para acelerar a ado\u00e7\u00e3o do WCM a contrata\u00e7\u00e3o e o envolvimento de pessoas altamente qualificadas, que entendam a metodologia, s\u00e3o mais do que necess\u00e1rias.&nbsp;<\/p>\n\n\n\n<p>Esses <strong>profissionais ser\u00e3o a base para a implementa\u00e7\u00e3o do WCM<\/strong> e os respons\u00e1veis por garantir que os objetivos est\u00e3o sendo seguidos.&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>5. Comprometimento da organiza\u00e7\u00e3o<\/strong><\/h4>\n\n\n\n<p>A melhoria cont\u00ednua proposta pelo WCM s\u00f3 acontece se os <strong>trabalhadores que movimentam a organiza\u00e7\u00e3o estiverem engajados.<\/strong> Por isso, a lideran\u00e7a precisa pensar em formas de garantir esse comprometimento.&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>6. Focar em melhoria cont\u00ednua para obter compet\u00eancia organizacional<\/strong><\/h4>\n\n\n\n<p>A <strong>cultura da melhoria<\/strong> cont\u00ednua deve ser amplamente estimulada entre os colaboradores, de forma gradual e em conjunto com a <strong>capacita\u00e7\u00e3o<\/strong> dos colaboradores que devem desenvolver as compet\u00eancias necess\u00e1rias para prevenir, resolver problemas e avaliar as solu\u00e7\u00f5es aplicadas.&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>7. Tempo e or\u00e7amento<\/strong><\/h4>\n\n\n\n<p>Desenvolver o WCM nas empresas demanda tempo e investimentos, sem isso \u00e9 imposs\u00edvel fazer a metodologia acontecer na pr\u00e1tica. Por isso, a lideran\u00e7a deve estar comprometida em <strong>dedicar tempo e <\/strong><a href=\"https:\/\/www.produttivo.com.br\/blog\/modelo-orcamento-prestacao-servicos\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>or\u00e7amento<\/strong><\/a><strong> ao projeto,<\/strong> afinal, vimos que ser\u00e3o necess\u00e1rios treinamentos, qualifica\u00e7\u00e3o de pessoas e investimento em melhorias para alcan\u00e7ar os resultados desejados.&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>8. N\u00edvel de detalhe<\/strong><\/h4>\n\n\n\n<p>Esse pilar chama a aten\u00e7\u00e3o para o n\u00edvel de detalhe que o WCM deve alcan\u00e7ar. \u00c9 preciso <strong>definir as etapas<\/strong> necess\u00e1rias para fazer o projeto acontecer, as metas a serem acompanhadas e o investimento necess\u00e1rio, tudo de forma detalhada, passo a passo.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-style-default\"><a href=\"https:\/\/materiais.produttivo.com.br\/modelo-checklist\/?utm_source=blog&amp;utm_medium=organic&amp;utm_term=postWCM&amp;utm_campaign=PostWCM\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" width=\"1024\" height=\"535\" data-src=\"https:\/\/www.produttivo.com.br\/blog\/wp-content\/uploads\/2023\/04\/Kit-checklist-de-manutencao-para-baixar-1024x535.webp\" alt=\"kit checklist de manuten\u00e7\u00e3o para baixar gratuitamente\" class=\"wp-image-21778 lazyload\" data-srcset=\"https:\/\/www.produttivo.com.br\/blog\/wp-content\/uploads\/2023\/04\/Kit-checklist-de-manutencao-para-baixar-1024x535.webp 1024w, https:\/\/www.produttivo.com.br\/blog\/wp-content\/uploads\/2023\/04\/Kit-checklist-de-manutencao-para-baixar-300x157.webp 300w, https:\/\/www.produttivo.com.br\/blog\/wp-content\/uploads\/2023\/04\/Kit-checklist-de-manutencao-para-baixar.webp 1200w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/535;\" \/><\/a><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>9. N\u00edvel de expans\u00e3o<\/strong><\/h4>\n\n\n\n<p>O n\u00edvel de expans\u00e3o diz respeito \u00e0 expans\u00e3o do projeto: qual \u00e1rea vai come\u00e7ar a implementar o WCM? Qual ser\u00e1 a ordem de setores que vai receber o WCM? Quais s\u00e3o os resultados que devem ser atingidos durante a implementa\u00e7\u00e3o do WCM?&nbsp;<\/p>\n\n\n\n<p>Todos esses questionamentos devem ser respondidos pela lideran\u00e7a para que sejam <strong>definidos come\u00e7os, finaliza\u00e7\u00f5es e pr\u00f3ximos passos<\/strong> e para que a implementa\u00e7\u00e3o do WCM n\u00e3o acabe logo no in\u00edcio, por n\u00e3o ter um vislumbre de para onde ir em seguida.&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>10. Motiva\u00e7\u00e3o da equipe&nbsp;<\/strong><\/h4>\n\n\n\n<p>E, por \u00faltimo, a motiva\u00e7\u00e3o da equipe deve ser sempre estimulada pela lideran\u00e7a, que precisa criar mecanismos para que os colaboradores se mantenham interessados e <strong>aplicando os pilares do WCM em seu dia a dia.&nbsp;<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Quais s\u00e3o as 7 ferramentas WCM?&nbsp;<\/strong><\/h2>\n\n\n\n<p>Existe uma variedade de ferramentas que podem ser utilizadas no WCM, tudo depende do objetivo de sua aplica\u00e7\u00e3o e do que voc\u00ea deseja alcan\u00e7ar com ela.&nbsp;<\/p>\n\n\n\n<p>\u00c9 comum que para cada fase da produ\u00e7\u00e3o um tipo de ferramenta possa ser aplicada e, em alguns casos, umas s\u00e3o mais ideais do que outras ou podem at\u00e9 mesmo ser utilizadas em conjunto.&nbsp;<\/p>\n\n\n\n<p>Para que voc\u00ea conhe\u00e7a as principais e mais utilizadas, separamos sete ferramentas principais:&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>5G<\/strong><\/h3>\n\n\n\n<p>A metodologia 5G ajuda a analisar o porqu\u00ea perdas, defeitos, avarias e anomalias acontecem, encontrando uma <strong>solu\u00e7\u00e3o definitiva para o problema <\/strong>em quest\u00e3o.&nbsp;<\/p>\n\n\n\n<p>Para isso, a ferramenta se utiliza de cinco defini\u00e7\u00f5es que t\u00eam como objetivo detalhar o problema e assim evidenciar a sua causa raiz. As conclus\u00f5es acontecem a partir de observa\u00e7\u00f5es realizadas no local em que o problema aconteceu e avalia\u00e7\u00f5es de registros ou documentos.&nbsp;<\/p>\n\n\n\n<p>Entenda o que cada defini\u00e7\u00e3o significa e quais a\u00e7\u00f5es devem ser tomadas para identificar o problema:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Gemba (F\u00e1brica):<\/strong> A primeira a\u00e7\u00e3o deve ser ir at\u00e9 o local em que aconteceu o problema e realizar sua pr\u00f3pria observa\u00e7\u00e3o;&nbsp;<\/li><li><strong>Gembutsu (Material):<\/strong> Em seguida avalie qual \u00e9 o problema, examinando-o e medindo-o;<\/li><li><strong>Genjitsu (Contexto):<\/strong> Analise dados e outras informa\u00e7\u00f5es que te ajudem a entender o que mudou, confira hist\u00f3ricos e demais registros;<\/li><li><strong>Genri (Teoria): <\/strong>Consulte os registros sobre os padr\u00f5es de produ\u00e7\u00e3o (desenho, especifica\u00e7\u00f5es, ciclos de trabalho)<\/li><li><strong>Gensoku (Regras e Princ\u00edpios):<\/strong> Verifique se os padr\u00f5es foram seguidos durante a produ\u00e7\u00e3o.&nbsp;<\/li><\/ul>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large is-style-default\"><a href=\"https:\/\/www.produttivo.com.br\/modelo\/checklist-de-maquinas-e-equipamentos\/?utm_source=blog&amp;utm_medium=organic&amp;utm_term=postWCM&amp;utm_campaign=PostWCM\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" width=\"1200\" height=\"627\" data-id=\"21708\" data-src=\"https:\/\/www.produttivo.com.br\/blog\/wp-content\/uploads\/2023\/04\/Checklist-digital-de-Maquinas-e-Equipamentos-para-usar-em-aplicativo.webp\" alt=\"checklist de m\u00e1quinas e equipamentos para usar em aplicativo\" class=\"wp-image-21708 lazyload\" data-srcset=\"https:\/\/www.produttivo.com.br\/blog\/wp-content\/uploads\/2023\/04\/Checklist-digital-de-Maquinas-e-Equipamentos-para-usar-em-aplicativo.webp 1200w, https:\/\/www.produttivo.com.br\/blog\/wp-content\/uploads\/2023\/04\/Checklist-digital-de-Maquinas-e-Equipamentos-para-usar-em-aplicativo-300x157.webp 300w, https:\/\/www.produttivo.com.br\/blog\/wp-content\/uploads\/2023\/04\/Checklist-digital-de-Maquinas-e-Equipamentos-para-usar-em-aplicativo-1024x535.webp 1024w\" data-sizes=\"(max-width: 1200px) 100vw, 1200px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1200px; --smush-placeholder-aspect-ratio: 1200\/627;\" \/><\/a><\/figure>\n<\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>5W2H<\/strong><\/h3>\n\n\n\n<p>Atrav\u00e9s de sete perguntas o <a href=\"https:\/\/www.produttivo.com.br\/blog\/plano-de-acao-5w2h\/\" target=\"_blank\" rel=\"noreferrer noopener\">5W2H<\/a> facilita a cria\u00e7\u00e3o e aplica\u00e7\u00e3o dos planos de a\u00e7\u00e3o, porque ao detalhar o que deve ser feito, as a\u00e7\u00f5es ficam muito mais claras.&nbsp;<\/p>\n\n\n\n<p>Veja quais s\u00e3o as perguntas que seu plano de a\u00e7\u00e3o deve responder:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>What? (O que?) &#8211; <\/strong>Se refere ao problema ou ao objetivo do plano de a\u00e7\u00e3o;<\/li><li><strong>Why? (Por qu\u00ea?) <\/strong>&#8211; Aqui devem ser elencadas as justificativas do projeto ou as explica\u00e7\u00f5es do porqu\u00ea aquele plano de a\u00e7\u00e3o foi escolhido;<\/li><li><strong>Where? (Onde?) &#8211;<\/strong> Pode ser tanto o local em que se encontra o problema ou o local\/setor que precisa atingir um objetivo;&nbsp;<\/li><li><strong>When? (Quando?) &#8211; <\/strong>Data de in\u00edcio e fim do plano de a\u00e7\u00e3o. Aqui podem ser definidas entregas menores, em etapas, dependendo do objetivo.&nbsp;<\/li><li><strong>Who? (Quem?) &#8211; <\/strong>Descri\u00e7\u00e3o dos envolvidos nos projetos e quais tarefas desempenham;&nbsp;<\/li><li><strong>How? (Como?) &#8211; <\/strong>Detalhamento de como a a\u00e7\u00e3o ser\u00e1 feita para alcan\u00e7ar o resultado almejado;&nbsp;<\/li><li><strong>How much? (Quanto?) &#8211; <\/strong>Qual o or\u00e7amento dispon\u00edvel para a realiza\u00e7\u00e3o das a\u00e7\u00f5es.&nbsp;<\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>5 Porqu\u00eas<\/strong><\/h3>\n\n\n\n<p>O <a href=\"https:\/\/www.produttivo.com.br\/blog\/5-porques\/\" target=\"_blank\" rel=\"noreferrer noopener\">5 porqu\u00eas<\/a> \u00e9 outra metodologia de an\u00e1lise de causa raiz que serve para chegar ao motivo exato que ocasionou aquele problema, de tal forma que ao resolv\u00ea-lo o problema \u00e9 definitivamente solucionado.&nbsp;<\/p>\n\n\n\n<p>Essa ferramenta determina que ao <strong>se perguntar pelo menos cinco vezes \u201cPor qu\u00ea?<\/strong>\u201d, a causa raiz do problema estar\u00e1 descoberta, isso porque a repeti\u00e7\u00e3o da pergunta faz com que as respostas sejam cada vez mais detalhadas e assertivas.&nbsp;<\/p>\n\n\n\n<p>Veja um exemplo pr\u00e1tico de sua aplica\u00e7\u00e3o no WCM:&nbsp;<\/p>\n\n\n\n<ol class=\"wp-block-list\"><li>O maquin\u00e1rio parou de funcionar. <strong>Por que o maquin\u00e1rio parou de funcionar?<\/strong><\/li><li>Porque depois de parar de funcionar enquanto estava sendo usado, identificamos que ao acionar o aparelho para iniciar novamente, ele n\u00e3o voltou a ligar. <strong>Por que n\u00e3o foi poss\u00edvel ligar o maquin\u00e1rio?&nbsp;<\/strong><\/li><li>Verificamos que uma pe\u00e7a estava quebrada. <strong>Por que a pe\u00e7a foi quebrada?&nbsp;<\/strong><\/li><li>A pe\u00e7a era muito antiga. <strong>Por que a pe\u00e7a era t\u00e3o antiga?<\/strong><\/li><li>Porque o <a href=\"https:\/\/www.produttivo.com.br\/blog\/inspecao-de-equipamentos\/\" target=\"_blank\" rel=\"noreferrer noopener\">maquin\u00e1rio n\u00e3o foi inspecionado<\/a>. <strong>Por que o maquin\u00e1rio n\u00e3o foi inspecionado?&nbsp;<\/strong><\/li><li>Porque <strong>n\u00e3o existe um plano de <\/strong><a href=\"https:\/\/www.produttivo.com.br\/blog\/manutencao-preventiva-quando-aplicar\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>manuten\u00e7\u00e3o preventiva<\/strong><\/a> para os maquin\u00e1rios da empresa.&nbsp;<\/li><\/ol>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Kaizen<\/strong><\/h3>\n\n\n\n<p>A metodologia Kaizen ajuda a empresa a <strong>colocar em pr\u00e1tica mudan\u00e7as<\/strong> que podem estar relacionadas a qualquer fase do processo de produ\u00e7\u00e3o. Sua aplica\u00e7\u00e3o ocorre em tr\u00eas fases principais:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Prepara\u00e7\u00e3o:<\/strong> Como o nome sugere, a fase de prepara\u00e7\u00e3o precede a implementa\u00e7\u00e3o da mudan\u00e7a e serve para preparar os profissionais envolvidos, fornecer informa\u00e7\u00f5es, apresentar as etapas de realiza\u00e7\u00e3o e coletar dados importantes para a pr\u00f3xima fase. A prepara\u00e7\u00e3o acontece em m\u00e9dia de 3 a 8 dias antes da mudan\u00e7a.&nbsp;<\/li><li><strong>Evento:<\/strong> \u00c9 quando a mudan\u00e7a \u00e9 implementada e tem dura\u00e7\u00e3o de 5 dias. Nessa fase o profissional deve se dedicar exclusivamente ao projeto<\/li><li><strong>Follow-up:<\/strong> O controle e as an\u00e1lises sobre a etapa de mudan\u00e7a acontecem no follow-up, que tem como objetivo garantir que as implementa\u00e7\u00f5es realizadas na fase anterior, continuem acontecendo e que a empresa n\u00e3o volte ao que estava antes de come\u00e7ar o projeto. O follow up leva entre 15 a 20 dias e demanda dedica\u00e7\u00e3o parcial da equipe.&nbsp;<\/li><\/ul>\n\n\n\n<figure class=\"wp-block-image size-large is-style-default\"><a href=\"https:\/\/materiais.produttivo.com.br\/modelo-checklist\/?utm_source=blog&amp;utm_medium=organic&amp;utm_term=postWCM&amp;utm_campaign=PostWCM\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" width=\"1024\" height=\"535\" data-src=\"https:\/\/www.produttivo.com.br\/blog\/wp-content\/uploads\/2023\/04\/Kit-checklist-de-manutencao-para-baixar-1024x535.webp\" alt=\"kit checklist de manuten\u00e7\u00e3o para baixar gratuitamente\" class=\"wp-image-21778 lazyload\" data-srcset=\"https:\/\/www.produttivo.com.br\/blog\/wp-content\/uploads\/2023\/04\/Kit-checklist-de-manutencao-para-baixar-1024x535.webp 1024w, https:\/\/www.produttivo.com.br\/blog\/wp-content\/uploads\/2023\/04\/Kit-checklist-de-manutencao-para-baixar-300x157.webp 300w, https:\/\/www.produttivo.com.br\/blog\/wp-content\/uploads\/2023\/04\/Kit-checklist-de-manutencao-para-baixar.webp 1200w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/535;\" \/><\/a><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>PDCA<\/strong><\/h3>\n\n\n\n<p>O PDCA \u00e9 muito utilizado na aplica\u00e7\u00e3o de planos de a\u00e7\u00e3o, de modo a estimular a melhoria cont\u00ednua, por isso \u00e9 um processo c\u00edclico, que nunca tem fim. Para implement\u00e1-lo \u00e9 necess\u00e1rio seguir as etapas descritas abaixo:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Plan (Planejar): <\/strong>Comece planejando quais a\u00e7\u00f5es ser\u00e3o implementadas, quais problemas devem ser solucionados, qual o objetivo do plano de a\u00e7\u00e3o e tamb\u00e9m as hip\u00f3teses que ser\u00e3o verificadas;<\/li><li><strong>Do (Fazer): <\/strong>Coloque em pr\u00e1tica o que foi planejado na fase anterior. N\u00e3o se esque\u00e7a de acompanhar e registrar os dados provenientes da a\u00e7\u00e3o para a fase seguinte;<\/li><li><strong>Check (Checar): <\/strong>Analise os dados coletados na fase \u201cDo\u201d e verifique se as metas e objetivos foram alcan\u00e7ados;<\/li><li><strong>At (Agir): <\/strong>Na \u00faltima fase \u00e9 necess\u00e1rio agir com base nos resultados do plano de a\u00e7\u00e3o. Caso seja necess\u00e1rio, fa\u00e7a ajustes com base nos aprendizados e comece novamente o projeto ou ent\u00e3o inicie um novo ciclo PDCA com a pr\u00f3xima demanda que deve ser solucionada.&nbsp;<\/li><\/ul>\n\n\n\n<p class=\"has-text-align-center\">Veja tamb\u00e9m: <a href=\"https:\/\/www.produttivo.com.br\/blog\/modelo-de-plano-de-acao\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Modelo de plano de a\u00e7\u00e3o: o que \u00e9, para que serve e como fazer?<\/strong><\/a><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>POP<\/strong><\/h3>\n\n\n\n<p>O <a href=\"https:\/\/www.produttivo.com.br\/blog\/pop-procedimento-operacional-padrao\/\" target=\"_blank\" rel=\"noreferrer noopener\">procedimento operacional padr\u00e3o (POP)<\/a> aplicado ao WCM \u00e9 utilizado para <strong>estabelecer rotinas claras de produ\u00e7\u00e3o e criar padr\u00f5es de opera\u00e7\u00e3o<\/strong> para, a partir disso, garantir que os erros humanos sejam reduzidos e que as a\u00e7\u00f5es identificadas como positivas dentro de cada \u00e1rea sejam mantidas.&nbsp;<\/p>\n\n\n\n<p>Para implementar o POP n\u00e3o existe segredo, basta criar um <strong>documento contendo o passo a passo das atividades rotineiras que a \u00e1rea em quest\u00e3o deve desenvolver.<\/strong> \u00c9 poss\u00edvel incrementar o documento acrescentando as seguintes informa\u00e7\u00f5es:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/www.produttivo.com.br\/blog\/modelo-de-checklist-exemplos-prontos\/\" target=\"_blank\" rel=\"noreferrer noopener\">Checklists<\/a> para verifica\u00e7\u00e3o do cumprimento do passo a passo das a\u00e7\u00f5es mapeadas;&nbsp;<\/li><li>Fluxograma com a representa\u00e7\u00e3o visual dos processos de cada \u00e1rea;<\/li><li>Gloss\u00e1rio com a explica\u00e7\u00e3o dos conceitos, siglas e jarg\u00f5es utilizados no documento;&nbsp;<\/li><li>Instru\u00e7\u00f5es de utiliza\u00e7\u00e3o do POP;<\/li><li>\u00cdndice para ajudar na localiza\u00e7\u00e3o das informa\u00e7\u00f5es;&nbsp;<\/li><li>Descri\u00e7\u00e3o do que deve ser evitado de fazer em cada atividade;<\/li><li>Pontos cr\u00edticos que podem surgir na realiza\u00e7\u00e3o da atividade e formas de resolv\u00ea-los;&nbsp;<\/li><li>Listagem de equipamentos e ferramentas necess\u00e1rias ao desenvolvimento de cada atividade;&nbsp;<\/li><li>Instru\u00e7\u00f5es de uso de equipamentos e <a href=\"https:\/\/www.produttivo.com.br\/blog\/controle-de-materiais\/\" target=\"_blank\" rel=\"noreferrer noopener\">materiais<\/a>;&nbsp;<\/li><li>Perguntas e respostas com as d\u00favidas mais comuns;&nbsp;<\/li><li>Assinatura dos respons\u00e1veis pela aprova\u00e7\u00e3o do POP.&nbsp;<\/li><\/ul>\n\n\n\n<p class=\"has-text-align-center\">Veja tamb\u00e9m: <a href=\"https:\/\/www.produttivo.com.br\/blog\/modelo-de-pop\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Modelo de POP: o que \u00e9 POP, qual a import\u00e2ncia e as vantagens?<\/strong><\/a><\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-style-default\"><a href=\"https:\/\/materiais.produttivo.com.br\/modelo-checklist\/?utm_source=blog&amp;utm_medium=organic&amp;utm_term=postWCM&amp;utm_campaign=PostWCM\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" width=\"1024\" height=\"535\" data-src=\"https:\/\/www.produttivo.com.br\/blog\/wp-content\/uploads\/2023\/04\/Kit-checklist-de-manutencao-para-baixar-1024x535.webp\" alt=\"kit checklist de manuten\u00e7\u00e3o para baixar gratuitamente\" class=\"wp-image-21778 lazyload\" data-srcset=\"https:\/\/www.produttivo.com.br\/blog\/wp-content\/uploads\/2023\/04\/Kit-checklist-de-manutencao-para-baixar-1024x535.webp 1024w, https:\/\/www.produttivo.com.br\/blog\/wp-content\/uploads\/2023\/04\/Kit-checklist-de-manutencao-para-baixar-300x157.webp 300w, https:\/\/www.produttivo.com.br\/blog\/wp-content\/uploads\/2023\/04\/Kit-checklist-de-manutencao-para-baixar.webp 1200w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/535;\" \/><\/a><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>5S<\/strong><\/h3>\n\n\n\n<p>O 5s combate \u00e0s perdas e desperd\u00edcios nas empresas ao focar na <strong>organiza\u00e7\u00e3o e na limpeza do ambiente de trabalho, <\/strong>contribuindo para o aumento de produtividade da equipe.&nbsp;<\/p>\n\n\n\n<p>Para implementar a ferramenta, siga os cinco conceitos abordados por ela:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Seiri (Senso de utiliza\u00e7\u00e3o): <\/strong>Para implementar o senso de utiliza\u00e7\u00e3o voc\u00ea deve remover do ambiente de trabalho tudo que n\u00e3o seja mais \u00fatil para a realiza\u00e7\u00e3o das <a href=\"https:\/\/www.produttivo.com.br\/blog\/controle-de-atividades\/\" target=\"_blank\" rel=\"noreferrer noopener\">atividades<\/a> (ferramentas e equipamentos quebrados, pe\u00e7as sem utilidade, m\u00f3veis antigos);<\/li><li><strong>Seiton (Senso de ordena\u00e7\u00e3o): <\/strong>Mantenha as coisas em seu devido lugar, estipulando um espa\u00e7o adequado para cada material utilizado durante as realiza\u00e7\u00e3o das atividades. Siga uma l\u00f3gica na defini\u00e7\u00e3o dos espa\u00e7os, de modo a facilitar a localiza\u00e7\u00e3o dos objetos;&nbsp;<\/li><li><strong>Seiso (Senso de limpeza): <\/strong>Mantenha sempre os equipamentos, m\u00f3veis e demais recursos da organiza\u00e7\u00e3o limpos e em boas condi\u00e7\u00f5es de uso.&nbsp;<\/li><li><strong>Seiketsu (Senso de padroniza\u00e7\u00e3o): <\/strong>Crie procedimentos padr\u00f5es na realiza\u00e7\u00e3o das atividades que contemplem a execu\u00e7\u00e3o dos tr\u00eas sensos anteriores, para que eles estejam sempre em funcionamento.&nbsp;<\/li><li><strong>Shitsuke (Senso de disciplina): <\/strong>Desenvolva uma cultura 5s na empresa tornando a execu\u00e7\u00e3o de todos os sensos um h\u00e1bito di\u00e1rio entre a equipe.&nbsp;<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Curso WCM: Quais s\u00e3o as certifica\u00e7\u00f5es?&nbsp;<\/strong><\/h2>\n\n\n\n<p>As certifica\u00e7\u00f5es do WCM s\u00e3o semelhantes \u00e0s do Seis Sigma, outra ferramenta de qualidade que \u00e9 alinhada aos princ\u00edpios do Lean Manufacturing. Por\u00e9m as fun\u00e7\u00f5es de cada n\u00edvel no WCM, s\u00e3o diferentes. Confira quais certifica\u00e7\u00f5es \u00e9 poss\u00edvel alcan\u00e7ar de acordo com os conhecimentos do WCM:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>White Belt (WB): <\/strong>S\u00e3o profissionais que entendem os conceitos e sabem aplicar as ferramentas do WCM de maneira independente, sem precisar de orienta\u00e7\u00f5es;&nbsp;<\/li><li><strong>Yellow Belt (YB): <\/strong>Para ser Yellow Belt o profissional precisa implementar um projeto com sucesso, seguindo um roteiro e tendo conhecimento te\u00f3rico sobre ele;<\/li><li><strong>Green Belt (GB): <\/strong>O Green Belt realiza atividades mais complexas e tem maiores responsabilidades. \u00c9 ele quem pode treinar e liderar os times de WCM;<\/li><li><strong>Black Belt (BB): <\/strong>Possui certifica\u00e7\u00e3o em quatro pilares WCM e al\u00e9m de treinar e liderar a equipe, pode certificar outros profissionais;&nbsp;<\/li><li><strong>Master Black Belt (MBB): <\/strong>S\u00e3o respons\u00e1veis por gerenciar os locais de atua\u00e7\u00e3o dos Black Belts, t\u00eam certifica\u00e7\u00e3o em 6 pilares do WCM e devem ter mais de dois anos de experi\u00eancia na implementa\u00e7\u00e3o do programa.&nbsp;<\/li><\/ul>\n\n\n\n<p class=\"has-text-align-center\">Leia tamb\u00e9m: <a href=\"https:\/\/www.produttivo.com.br\/blog\/automacao-industrial\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Tudo sobre automa\u00e7\u00e3o industrial: o que \u00e9, objetivos e vantagens<\/strong><\/a><strong>&nbsp;<\/strong><\/p>\n\n\n\n<p>Al\u00e9m do WCM temos outra dica que pode te ajudar a <strong>otimizar seus resultados de manuten\u00e7\u00e3o:<\/strong> o software do <a href=\"https:\/\/www.produttivo.com.br\/?utm_source=blog&amp;utm_medium=organic&amp;utm_term=postWCM&amp;utm_campaign=PostWCM\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Produttivo<\/strong><\/a>. Nele voc\u00ea consegue agendar manuten\u00e7\u00f5es peri\u00f3dicas, controlar o andamento das atividades e criar relat\u00f3rios e <a href=\"https:\/\/www.produttivo.com.br\/modelo\/checklist-manutencao-preventiva\/?utm_source=blog&amp;utm_medium=organic&amp;utm_term=postWCM&amp;utm_campaign=PostWCM\" target=\"_blank\" rel=\"noreferrer noopener\">checklists de manuten\u00e7\u00e3o<\/a> de forma ilimitada.&nbsp;<\/p>\n\n\n\n<p><a href=\"https:\/\/www.produttivo.com.br\/cadastro\/?utm_source=blog&amp;utm_medium=organic&amp;utm_term=postWCM&amp;utm_campaign=PostWCM\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Teste gr\u00e1tis<\/strong><\/a> por 15 dias e veja resultados por toda a opera\u00e7\u00e3o!&nbsp;<\/p>\n\n\n\n<script type=\"application\/ld+json\">\n{\n  \"@context\": \"https:\/\/schema.org\",\n  \"@type\": \"FAQPage\",\n  \"mainEntity\": [{\n    \"@type\": \"Question\",\n    \"name\": \"WCM o que \u00e9?\",\n    \"acceptedAnswer\": {\n      \"@type\": \"Answer\",\n      \"text\": \"O WCM (World Class Manufacturing) \u00e9 uma metodologia que re\u00fane princ\u00edpios e t\u00e9cnicas de gest\u00e3o a serem aplicadas em empresas com o objetivo de eliminar desperd\u00edcios, reduzir custos e melhorar processos.\"\n    }\n  },{\n    \"@type\": \"Question\",\n    \"name\": \"Qual a diferen\u00e7a entre TPM e WCM?\",\n    \"acceptedAnswer\": {\n      \"@type\": \"Answer\",\n      \"text\": \"A manuten\u00e7\u00e3o produtiva total (TPM) \u00e9 um conjunto de a\u00e7\u00f5es que t\u00eam como objetivo minimizar erros e aumentar a produtividade de equipamentos atrav\u00e9s do estabelecimento de rotinas de manuten\u00e7\u00e3o e do acompanhamento de performance dos ativos. \n\nJ\u00e1 o WCM, como vimos, \u00e9 uma metodologia que pode ser aplicada em todo o processo produtivo, independente do setor. Seu prop\u00f3sito \u00e9 alcan\u00e7ar excel\u00eancia operacional na produ\u00e7\u00e3o, no controle de qualidade, na log\u00edstica e nas rotinas de manuten\u00e7\u00e3o.\"\n    }\n  },{\n    \"@type\": \"Question\",\n    \"name\": \"Qual a diferen\u00e7a entre Lean e WCM?\",\n    \"acceptedAnswer\": {\n      \"@type\": \"Answer\",\n      \"text\": \"O WCM surgiu a partir do sistema Lean, replicando para a sua metodologia o conceito j\u00e1 consolidado de melhoria cont\u00ednua. A diferen\u00e7a \u00e9 que a metodologia WCM foi criada especialmente para atender as necessidades e caracter\u00edsticas do mercado ocidental, que demandava resultados r\u00e1pidos, utilizando a menor quantidade de recursos poss\u00edveis.\"\n    }\n  },{\n    \"@type\": \"Question\",\n    \"name\": \"Quais s\u00e3o os benef\u00edcios da gest\u00e3o WCM nas empresas?\",\n    \"acceptedAnswer\": {\n      \"@type\": \"Answer\",\n      \"text\": \"<ul>\n<li>Redu\u00e7\u00e3o nos custos de manuten\u00e7\u00e3o;<\/li>\n<li>Melhora de seguran\u00e7a para os operadores; <\/li>\n<li>Diminui\u00e7\u00e3o de desperd\u00edcios;<\/li>\n<li>Melhora na qualidade dos produtos; <\/li>\n<li>Redu\u00e7\u00e3o na necessidade de manuten\u00e7\u00f5es corretivas; <\/li>\n<li>Resolu\u00e7\u00e3o de problemas feitos de maneira mais r\u00e1pida;  <\/li>\n<li>Otimiza\u00e7\u00e3o de processos;<\/li>\n<li>Aumento de produtividade; <\/li>\n<li>Melhora no desempenho dos ativos; <\/li>\n<li>Redu\u00e7\u00e3o de paradas n\u00e3o programadas;<\/li>\n<li>Aumento de satisfa\u00e7\u00e3o dos clientes; <\/li>\n<li>Redu\u00e7\u00e3o de lead time;<\/li>\n<li>Redu\u00e7\u00e3o de produtos em estoque; <\/li>\n<li>Entre outros.<\/li>\n<\/ul>\"\n    }\n  },{\n    \"@type\": \"Question\",\n    \"name\": \"Como implementar a metodologia WCM na sua empresa?\",\n    \"acceptedAnswer\": {\n      \"@type\": \"Answer\",\n      \"text\": \"<ul>\n<li>Escolha a \u00e1rea que servir\u00e1 de modelo para a implementa\u00e7\u00e3o do WCM. Opte pelo setor que apresenta mais problemas, resultados insatisfat\u00f3rios ou os gargalos mais recorrentes, porque ser\u00e3o \u00e1reas que apresentar\u00e3o maiores oportunidades de melhorias;<\/li>\n<li>Comece a estrutura a aplica\u00e7\u00e3o da metodologia atrav\u00e9s de um planejamento que leve em conta todos os princ\u00edpios do WCM (mais para frente elencamos todos os princ\u00edpios para voc\u00ea n\u00e3o esquecer de nenhum);<\/li>\n<li>Entenda e defina quais a\u00e7\u00f5es podem ser implementadas levando em conta os princ\u00edpios do WCM e os objetivos da empresa (redu\u00e7\u00e3o de falhas, perdas, desperd\u00edcios, defeitos, gera\u00e7\u00e3o de res\u00edduos, etc);<\/li>\n<li>Capacite os profissionais da \u00e1rea oferecendo treinamentos sobre WCM para que conhe\u00e7am e apliquem as ferramentas necess\u00e1rias; <\/li>\n<li>Garanta que profissionais altamente qualificados sejam alocados para esse setor e que eles auxiliem na implementa\u00e7\u00e3o das t\u00e9cnicas de WCM; <\/li>\n<li>Use ferramentas que possam auxiliar na implementa\u00e7\u00e3o dos princ\u00edpios do WCM (mais adiante falaremos de algumas delas detalhadamente). S\u00e3o exemplos o FMEA, Matriz GUT, 5s 5t, Poka Yoke, Kanban e an\u00e1lise de causa raiz.<\/li>\n<\/ul>\"\n    }\n  },{\n    \"@type\": \"Question\",\n    \"name\": \"Como \u00e9 o sistema de avalia\u00e7\u00e3o WCM?\",\n    \"acceptedAnswer\": {\n      \"@type\": \"Answer\",\n      \"text\": \"A avalia\u00e7\u00e3o do WCM \u00e9 realizada por uma auditoria externa que faz uma an\u00e1lise, duas vezes por ano, sobre os resultados obtidos em cada um dos pilares do WCM. \n\nA nota vai de 0 a 5 e todos os pilares s\u00e3o avaliados individualmente considerando o n\u00edvel de expans\u00e3o, profundidade e maturidade dos princ\u00edpios adotados...\"\n    }\n  },{\n    \"@type\": \"Question\",\n    \"name\": \"Quais s\u00e3o os pilares do WCM?\",\n    \"acceptedAnswer\": {\n      \"@type\": \"Answer\",\n      \"text\": \"Pilares t\u00e9cnicos do WCM: \n<ul>\n<li>1. Seguran\u00e7a;<\/li>\n<li>2. Desdobramento de custos;<\/li>\n<li>3. Melhoria cont\u00ednua;<\/li>\n<li>4. Manuten\u00e7\u00e3o Aut\u00f4noma;<\/li>\n<li>5. Manuten\u00e7\u00e3o Planejada;<\/li>\n<li>6. Controle de qualidade;<\/li>\n<li>7. Log\u00edstica e servi\u00e7o ao cliente;<\/li>\n<li>8. Gest\u00e3o preventiva dos equipamentos;<\/li>\n<li>9. Desenvolvimento de pessoas;<\/li>\n<li>10. Meio ambiente e energia.<\/li>\n<\/ul>\nPilares gerenciais do WCM\n<ul>\n<li>1. Comprometimento gerencial;<\/li>\n<li>2. Clareza de objetivos;<\/li>\n<li>3. Mapeamento das etapas para o WCM;<\/li>\n<li>4. Aloca\u00e7\u00e3o de pessoas qualificadas;<\/li>\n<li>5. Comprometimento da organiza\u00e7\u00e3o;<\/li>\n<li>6. Focar em melhoria cont\u00ednua para obter compet\u00eancia organizacional;<\/li>\n<li>7. Tempo e or\u00e7amento;<\/li>\n<li>8. N\u00edvel de detalhe;<\/li>\n<li>9. N\u00edvel de expans\u00e3o;<\/li>\n<li>10. Motiva\u00e7\u00e3o da equipe.<\/li>\n<\/ul>\"\n    }\n  },{\n    \"@type\": \"Question\",\n    \"name\": \"Quais s\u00e3o as 7 ferramentas WCM?\",\n    \"acceptedAnswer\": {\n      \"@type\": \"Answer\",\n      \"text\": \"<ul>\n<li>5G;<\/li>\n<li>5W2H;<\/li>\n<li>5 Porqu\u00eas;<\/li>\n<li>Kaizen;<\/li>\n<li>PDCA;<\/li>\n<li>POP;<\/li>\n<li>5S.<\/li>\n<\/ul>\"\n    }\n  },{\n    \"@type\": \"Question\",\n    \"name\": \"Curso WCM: Quais s\u00e3o as certifica\u00e7\u00f5es?\",\n    \"acceptedAnswer\": {\n      \"@type\": \"Answer\",\n      \"text\": \"<ul>\n<li>White Belt (WB): S\u00e3o profissionais que entendem os conceitos e sabem aplicar as ferramentas do WCM de maneira independente, sem precisar de orienta\u00e7\u00f5es; <\/li>\n<li>Yellow Belt (YB): Para ser Yellow Belt o profissional precisa implementar um projeto com sucesso, seguindo um roteiro e tendo conhecimento te\u00f3rico sobre ele;<\/li>\n<li>Green Belt (GB): O Green Belt realiza atividades mais complexas e tem maiores responsabilidades. \u00c9 ele quem pode treinar e liderar os times de WCM;<\/li>\n<li>Black Belt (BB): Possui certifica\u00e7\u00e3o em quatro pilares WCM e al\u00e9m de treinar e liderar a equipe, pode certificar outros profissionais; <\/li>\n<li>Master Black Belt (MBB): S\u00e3o respons\u00e1veis por gerenciar os locais de atua\u00e7\u00e3o dos Black Belts, t\u00eam certifica\u00e7\u00e3o em 6 pilares do WCM e devem ter mais de dois anos de experi\u00eancia na implementa\u00e7\u00e3o do programa.<\/li>\n<\/ul>\"\n    }\n  }]\n}\n<\/script>\n","protected":false},"excerpt":{"rendered":"<p>Reduzir custos, cortar desperd\u00edcios e aumentar a efici\u00eancia da produ\u00e7\u00e3o n\u00e3o precisa ser uma meta distante \u2014 existe uma metodologia [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":21832,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[575],"tags":[],"class_list":["post-21829","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gestao-da-qualidade"],"uagb_featured_image_src":{"full":["https:\/\/www.produttivo.com.br\/blog\/wp-content\/uploads\/2023\/04\/WCM-Manutencao-de-classe-mundial.webp",900,600,false],"thumbnail":["https:\/\/www.produttivo.com.br\/blog\/wp-content\/uploads\/2023\/04\/WCM-Manutencao-de-classe-mundial-150x150.webp",150,150,true],"medium":["https:\/\/www.produttivo.com.br\/blog\/wp-content\/uploads\/2023\/04\/WCM-Manutencao-de-classe-mundial-300x200.webp",300,200,true],"medium_large":["https:\/\/www.produttivo.com.br\/blog\/wp-content\/uploads\/2023\/04\/WCM-Manutencao-de-classe-mundial.webp",900,600,false],"large":["https:\/\/www.produttivo.com.br\/blog\/wp-content\/uploads\/2023\/04\/WCM-Manutencao-de-classe-mundial.webp",900,600,false],"1536x1536":["https:\/\/www.produttivo.com.br\/blog\/wp-content\/uploads\/2023\/04\/WCM-Manutencao-de-classe-mundial.webp",900,600,false],"2048x2048":["https:\/\/www.produttivo.com.br\/blog\/wp-content\/uploads\/2023\/04\/WCM-Manutencao-de-classe-mundial.webp",900,600,false]},"uagb_author_info":{"display_name":"Heloiza da Silva","author_link":"https:\/\/www.produttivo.com.br\/blog\/author\/heloiza-silva\/"},"uagb_comment_info":0,"uagb_excerpt":"Reduzir custos, cortar desperd\u00edcios e aumentar a efici\u00eancia da produ\u00e7\u00e3o n\u00e3o precisa ser uma meta distante \u2014 existe uma metodologia [&hellip;]","_links":{"self":[{"href":"https:\/\/www.produttivo.com.br\/blog\/wp-json\/wp\/v2\/posts\/21829","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.produttivo.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.produttivo.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.produttivo.com.br\/blog\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.produttivo.com.br\/blog\/wp-json\/wp\/v2\/comments?post=21829"}],"version-history":[{"count":5,"href":"https:\/\/www.produttivo.com.br\/blog\/wp-json\/wp\/v2\/posts\/21829\/revisions"}],"predecessor-version":[{"id":27828,"href":"https:\/\/www.produttivo.com.br\/blog\/wp-json\/wp\/v2\/posts\/21829\/revisions\/27828"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.produttivo.com.br\/blog\/wp-json\/wp\/v2\/media\/21832"}],"wp:attachment":[{"href":"https:\/\/www.produttivo.com.br\/blog\/wp-json\/wp\/v2\/media?parent=21829"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.produttivo.com.br\/blog\/wp-json\/wp\/v2\/categories?post=21829"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.produttivo.com.br\/blog\/wp-json\/wp\/v2\/tags?post=21829"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}